{"id":238,"date":"2022-12-20T15:52:26","date_gmt":"2022-12-20T13:52:26","guid":{"rendered":"https:\/\/werkado.eu\/238-2\/"},"modified":"2025-06-17T10:22:16","modified_gmt":"2025-06-17T08:22:16","slug":"edasimuujale","status":"publish","type":"page","link":"https:\/\/werkado.eu\/lv\/","title":{"rendered":"D\u012bleriem"},"content":{"rendered":"\n<div class=\"banner-main\" class=\"banner-block, flex\"\n    style=\"background-color: #f8fbff\">\n    <div class=\"banner-container\">\n        <h1 class=\"banner-title\">\n            J\u016bsu augst\u0101k\u0101s kvalit\u0101tes darbar\u012bku vairumtirdzniec\u012bbas partneris Baltijas valst\u012bs        <\/h1>\n        <p class=\"bannerl-description lead\">\n            Profesion\u0101\u013cu atzin\u012bgi nov\u0113rt\u0113ti darbar\u012bki un individu\u0101lie aizsardz\u012bbas l\u012bdzek\u013ci vienuviet! \r\nK\u0101 ar\u012b atbalsta pakalpojumi \u0113rtai un efekt\u012bvai pas\u016bt\u012b\u0161anai un p\u0101rdo\u0161anas atbalstam.\r\nVai esat gatavs pacelt savu biznesu n\u0101kamaj\u0101 l\u012bmen\u012b?        <\/p>\n        <div class=\"button-container banner-button\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/werkado.eu\/lv\/kontakt\/\" role=\"button\" class=\"btn-main\">\n\t\t\t\t\t<div class=\"btn-wrapper\">\n\t\t\t\t\t\t<span>K\u013c\u016bstiet par m\u016bsu partneri!<\/span>\n\t\t\t\t\t\t<div class=\"arrow-logo\">\n\t\t\t\t\t\t\t<svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M14.2982 5.29289C13.908 4.90237 13.2753 4.90237 12.8851 5.29289C12.4949 5.68342 12.4949 6.31658 12.8851 6.70711L17.1746 11H3.99921C3.44736 11 3 11.4477 3 12C3 12.5523 3.44736 13 3.99921 13H17.1746L12.8851 17.2929C12.4949 17.6834 12.4949 18.3166 12.8851 18.7071C13.2753 19.0976 13.908 19.0976 14.2982 18.7071L21 12L14.2982 5.29289Z\" fill=\"#F9FBFF\"\/>\n<\/svg>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\n\t\t\t\t\t\t\t<a href=\"https:\/\/werkado.eu\/lv\/services\/werkado-vending\/\" role=\"button\" class=\"btn-main secondary\">\n\t\t\t\t\t<div class=\"btn-wrapper\">\n\t\t\t\t\t\t<span>Atkl\u0101j vendingu<\/span>\n\t\t\t\t\t\t<div class=\"arrow-logo\">\n\t\t\t\t\t\t\t<svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M14.2982 5.29289C13.908 4.90237 13.2753 4.90237 12.8851 5.29289C12.4949 5.68342 12.4949 6.31658 12.8851 6.70711L17.1746 11H3.99921C3.44736 11 3 11.4477 3 12C3 12.5523 3.44736 13 3.99921 13H17.1746L12.8851 17.2929C12.4949 17.6834 12.4949 18.3166 12.8851 18.7071C13.2753 19.0976 13.908 19.0976 14.2982 18.7071L21 12L14.2982 5.29289Z\" fill=\"#F9FBFF\"\/>\n<\/svg>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\n        <div class=\"arrow-down\">\n            <img decoding=\"async\" src=\"https:\/\/werkado.eu\/wp-content\/themes\/werkado\/assets\/dist\/images\/arrow-down.png\" alt=\"\" \/>\n        <\/div>\n    <\/div>\n    <div class=\"banner-image\">\n        <img fetchpriority=\"high\" decoding=\"async\" width=\"558\" height=\"664\" src=\"https:\/\/werkado.eu\/wp-content\/uploads\/2023\/01\/main_illustration.png\" class=\"attachment-full size-full\" alt=\"T\u00f6\u00f6riistad banner pilt\" loading=\"eager\" srcset=\"https:\/\/werkado.eu\/wp-content\/uploads\/2023\/01\/main_illustration.png 558w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/01\/main_illustration-252x300.png 252w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/01\/main_illustration-34x40.png 34w\" sizes=\"(max-width: 558px) 100vw, 558px\" \/>    <\/div>\n    <div class=\"banner-bg\">\n        <img decoding=\"async\" src=\"https:\/\/werkado.eu\/wp-content\/themes\/werkado\/assets\/dist\/images\/werkado-banner-bg.png\" alt=\"\" \/>\n    <\/div>\n<\/div>\n\n<section class=\"banner-block\">\n    <div class=\"numbers-wrapper\">\n        <div class=\"number\">\n            20 000+        <\/div>\n        <div class=\"numbers-title\">produkti m\u016bsu kl\u0101st\u0101<\/div>\n    <\/div>\n    <div>\n        <div class=\"number\">\n            15+        <\/div>\n        <div class=\"numbers-title\">darb\u012bbas gadi<\/div>\n    <\/div>\n    <div>\n        <div class=\"number\">\n            20+        <\/div>\n        <div class=\"numbers-title\">z\u012bmoli<\/div>\n    <\/div>\n    <div>\n        <div class=\"number\">\n            350+        <\/div>\n        <div class=\"numbers-title\">akt\u012bvi klienti Baltijas valst\u012bs<\/div>\n    <\/div>\n<\/section>\n\n\n<section class=\"service_container\"\n    style=\"background-size:cover; background-repeat: no-repeat; background-image: url(https:\/\/werkado.eu\/wp-content\/themes\/werkado\/assets\/dist\/images\/hulgimuuk_tagataust.jpg)\">\n    <article class=\"wholesale-container\">\n        <h2>\n            M\u0113s pal\u012bdz\u0113sim att\u012bst\u012bt j\u016bsu biznesu!        <\/h2>\n        <ul>\n            <li>\n                <div class=\"service_description\">\n                    Optimiz\u0113ti biznesa procesi d\u012bleriem                <\/div>\n            <\/li>\n            <li>\n                <div class=\"service_description\">\n                    M\u016bsdien\u012bga datu apmai\u0146a interneta veikaliem                <\/div>\n            <\/li>\n            <li>\n                <div class=\"service_description\">\n                    5 000+ produktu noliktav\u0101 katru dienu                <\/div>\n            <\/li>\n            <li>\n                <div class=\"service_description\">\n                    Noliktav\u0101 eso\u0161o pre\u010du pieg\u0101de 24h laik\u0101                <\/div>\n            <\/li>\n        <\/ul>\n        <div class=\"button-container\">\n                    <a href=\"https:\/\/werkado.eu\/lv\/kontakt\/\" role=\"button\" class=\"btn-main btn-white\">\n                <div class=\"btn-wrapper\">\n                    <span>\n                        K\u013c\u016bstiet par m\u016bsu partneri!                    <\/span>\n                    <div class=\"arrow-logo\">\n                        <svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M14.2982 5.29289C13.908 4.90237 13.2753 4.90237 12.8851 5.29289C12.4949 5.68342 12.4949 6.31658 12.8851 6.70711L17.1746 11H3.99921C3.44736 11 3 11.4477 3 12C3 12.5523 3.44736 13 3.99921 13H17.1746L12.8851 17.2929C12.4949 17.6834 12.4949 18.3166 12.8851 18.7071C13.2753 19.0976 13.908 19.0976 14.2982 18.7071L21 12L14.2982 5.29289Z\" fill=\"#004BD1\"\/>\n<\/svg>\n                    <\/div>\n                <\/div>\n            <\/a>\n                                <\/div>\n    <\/article>\n    <article class=\"additional-services-container\">\n        <h2>\n            Atbalsta pakalpojumi:         <\/h2>\n                                    <div class=\"services_list\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"65\" src=\"https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Werkado-muugi-ja-turundustugi-65x65.png\" class=\"attachment-service_icon size-service_icon wp-post-image\" alt=\"\" srcset=\"https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Werkado-muugi-ja-turundustugi-65x65.png 65w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Werkado-muugi-ja-turundustugi-300x300.png 300w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Werkado-muugi-ja-turundustugi-150x150.png 150w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Werkado-muugi-ja-turundustugi-40x40.png 40w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Werkado-muugi-ja-turundustugi.png 640w\" sizes=\"auto, (max-width: 65px) 100vw, 65px\" \/>                    <div class=\"services_list_with_icons\">\n                        P\u0101rdo\u0161anas un m\u0101rketinga atbalsts                    <\/div>\n                <\/div>\n                            <div class=\"services_list\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"65\" src=\"https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Werkado-b2b-iseteenindus-65x65.png\" class=\"attachment-service_icon size-service_icon wp-post-image\" alt=\"\" srcset=\"https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Werkado-b2b-iseteenindus-65x65.png 65w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Werkado-b2b-iseteenindus-300x300.png 300w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Werkado-b2b-iseteenindus-150x150.png 150w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Werkado-b2b-iseteenindus-40x40.png 40w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Werkado-b2b-iseteenindus.png 640w\" sizes=\"auto, (max-width: 65px) 100vw, 65px\" \/>                    <div class=\"services_list_with_icons\">\n                        B2B pa\u0161apkalpo\u0161an\u0101s vide                    <\/div>\n                <\/div>\n                            <div class=\"services_list\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"65\" src=\"https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Werkado-dropship-65x65.png\" class=\"attachment-service_icon size-service_icon wp-post-image\" alt=\"\" srcset=\"https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Werkado-dropship-65x65.png 65w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Werkado-dropship-300x300.png 300w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Werkado-dropship-150x150.png 150w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Werkado-dropship-40x40.png 40w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Werkado-dropship.png 640w\" sizes=\"auto, (max-width: 65px) 100vw, 65px\" \/>                    <div class=\"services_list_with_icons\">\n                        Tie\u0161\u0101 pieg\u0101de (Dropshipping)                    <\/div>\n                <\/div>\n                            <div class=\"services_list\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"65\" src=\"https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Werkado-xml-liidestus-65x65.png\" class=\"attachment-service_icon size-service_icon wp-post-image\" alt=\"\" srcset=\"https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Werkado-xml-liidestus-65x65.png 65w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Werkado-xml-liidestus-300x300.png 300w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Werkado-xml-liidestus-150x150.png 150w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Werkado-xml-liidestus-40x40.png 40w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Werkado-xml-liidestus.png 640w\" sizes=\"auto, (max-width: 65px) 100vw, 65px\" \/>                    <div class=\"services_list_with_icons\">\n                        XML saskarne                    <\/div>\n                <\/div>\n                            <div class=\"services_list\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"65\" src=\"https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Werkado-jarelteenindus-65x65.png\" class=\"attachment-service_icon size-service_icon wp-post-image\" alt=\"Ja\u0308relteenindus\" srcset=\"https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Werkado-jarelteenindus-65x65.png 65w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Werkado-jarelteenindus-300x300.png 300w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Werkado-jarelteenindus-150x150.png 150w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Werkado-jarelteenindus-40x40.png 40w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Werkado-jarelteenindus.png 640w\" sizes=\"auto, (max-width: 65px) 100vw, 65px\" \/>                    <div class=\"services_list_with_icons\">\n                        P\u0113cp\u0101rdo\u0161anas apkalpo\u0161ana                    <\/div>\n                <\/div>\n                            <div class=\"button-container center-element\">\n                    <a href=\"https:\/\/werkado.eu\/lv\/kontakt\/\" role=\"button\" class=\"btn-main\">\n                <div class=\"btn-wrapper\">\n                    <span>\n                        Vair\u0101k inform\u0101cija par pakalpojumiem                    <\/span>\n                    <div class=\"arrow-logo\">\n                        <svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M14.2982 5.29289C13.908 4.90237 13.2753 4.90237 12.8851 5.29289C12.4949 5.68342 12.4949 6.31658 12.8851 6.70711L17.1746 11H3.99921C3.44736 11 3 11.4477 3 12C3 12.5523 3.44736 13 3.99921 13H17.1746L12.8851 17.2929C12.4949 17.6834 12.4949 18.3166 12.8851 18.7071C13.2753 19.0976 13.908 19.0976 14.2982 18.7071L21 12L14.2982 5.29289Z\" fill=\"#F9FBFF\"\/>\n<\/svg>\n                    <\/div>\n                <\/div>\n            <\/a>\n                    <\/div>\n    <\/article>\n<\/section>\n\n\n<div style=\"height:0px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<section class=\"section-brands\">\n    <h2 class=\"text-center\">\n        Z\u012bmoli    <\/h2>\n    <div class=\"brand-links-wrapper\">\n                                    <div class=\"brand-link\">\n                                                                <a href=\"https:\/\/werkado.eu\/lv\/brands\/ansell\/\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"91\" src=\"https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Ansell-300x91.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Ansell-300x91.png 300w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Ansell-131x40.png 131w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Ansell.png 414w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                        <\/a>\n                                    <\/div>\n                            <div class=\"brand-link\">\n                                                                <a href=\"https:\/\/werkado.eu\/lv\/brands\/bahco\/\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"57\" src=\"https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Bahco-1-300x57.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Bahco-1-300x57.png 300w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Bahco-1-211x40.png 211w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Bahco-1.png 664w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                        <\/a>\n                                    <\/div>\n                            <div class=\"brand-link\">\n                                                                <a href=\"https:\/\/werkado.eu\/lv\/brands\/mechanixwear\/\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"116\" src=\"https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/mechanix-1-300x116.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/mechanix-1-300x116.png 300w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/mechanix-1-65x25.png 65w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/mechanix-1-103x40.png 103w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/mechanix-1.png 325w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                        <\/a>\n                                    <\/div>\n                            <div class=\"brand-link\">\n                                                                <a href=\"https:\/\/werkado.eu\/lv\/brands\/piher\/\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"64\" src=\"https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Piher-black-300x64.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Piher-black-300x64.png 300w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Piher-black-188x40.png 188w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Piher-black.png 592w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                        <\/a>\n                                    <\/div>\n                            <div class=\"brand-link\">\n                                                                <a href=\"https:\/\/werkado.eu\/lv\/brands\/wera\/\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"275\" height=\"126\" src=\"https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Wera.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Wera.png 275w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/02\/Wera-87x40.png 87w\" sizes=\"auto, (max-width: 275px) 100vw, 275px\" \/>                        <\/a>\n                                    <\/div>\n                        <\/div>\n    <div class=\"center-element\">\n        <\/div>\n<\/section>\n\n\n<!-- SwiperJS CDN -->\n\n<link rel=\"stylesheet\" href=\"https:\/\/cdn.jsdelivr.net\/npm\/swiper@8\/swiper-bundle.min.css\" \/>\n<script src=\"https:\/\/cdn.jsdelivr.net\/npm\/swiper@8\/swiper-bundle.min.js\"><\/script>\n\n<section class=\" feedback-container container-fluid\">\n    <div class=\"swiper mySwiper\">\n    <div class=\"swiper-wrapper\">\n                        <div class=\"swiper-slide\">\n            <div>\n              \n<p><\/p>\n\n<p class=\"has-text-align-center\">\u201cWerkado ir m\u016bsu partneris kop\u0161 2015. gada, un  mums par vi\u0146iem ir  tikai pozit\u012bvi koment\u0101ri.&#13;\nWerkado ir pan\u0101cis ide\u0101lu nopietn\u012bbas un profesion\u0101la uz\u0146\u0113muma kombin\u0101ciju, ko vada draudz\u012bga un ap\u0146\u0113m\u012bga lielisku cilv\u0113ku komanda.&#13;\nM\u0113s, Piher, esam piln\u012bb\u0101 apmierin\u0101ti ar m\u016bsu ikdienas sadarb\u012bbu un daudzajiem pas\u0101kumiem, ko vi\u0146i katru gadu organiz\u0113, lai veicin\u0101tu m\u016bsu p\u0101rdo\u0161anas apjomus Baltijas valst\u012bs.\u201d<\/p>\n\n<p><br\/><strong>Laura Manso<\/strong><\/p>\n\n<p><\/p>\n\n<p><\/p>\n\n<p><\/p>\n\n<p><\/p>\n            <\/div>\n            <p class=\"reviewer\">Piher (INDUSTRIAS PIQUERAS, S.A)<\/p>\n            <p class=\"company\">\n                        <\/p>\n          <\/div>\n                  <div class=\"swiper-slide\">\n            <div>\n              \n<p class=\"has-text-align-center\">\u201cMums pat\u012bk vienm\u0113r \u0101trais, pozit\u012bvais un konstrukt\u012bvais dialogs ar Werkado. Snap-on bija nepiecie\u0161ams uzticams viet\u0113jais partneris Baltijas valst\u012bs ar past\u0101vo\u0161u t\u012bklu un sakariem, kas ir noder\u012bgi m\u016bsu korpor\u0101cijai. Str\u0101d\u0101jot komand\u0101, m\u0113s esam iev\u0113rojami palielin\u0101ju\u0161i savu biznesu un, cerams, turpin\u0101sim savu izaugsmi.\u201d&#13;\n<\/p>\n\n<p><strong>Ole Schonwandt<\/strong><\/p>\n            <\/div>\n            <p class=\"reviewer\">Snap-on<\/p>\n            <p class=\"company\">\n                        <\/p>\n          <\/div>\n                  <div class=\"swiper-slide\">\n            <div>\n              \n<p class=\"has-text-align-center\">\u201cM\u0113s augstu nov\u0113rt\u0113jam Werkado komandas garu \u2013 lieliski cilv\u0113ki, kas p\u0101rdod lieliskus produktus! Vi\u0146i ir \u013coti profesion\u0101li, cent\u012bgi un god\u012bgi partneri, kas vienm\u0113r mekl\u0113 abpus\u0113ji izdev\u012bgus risin\u0101jumus. Kapro ir k\u013cuvis par vienu no visvair\u0101k p\u0101rdotajiem m\u0113rinstrumentu z\u012bmoliem, ko p\u0101rdod gan lielajos DIY veikalu t\u012bklos, gan tradicion\u0101lajos veikalos.\u201d<\/p>\n\n<p><\/p>\n\n<p><strong>Oleg Shpits<\/strong><\/p>\n            <\/div>\n            <p class=\"reviewer\">Kapro Industries Ltd<\/p>\n            <p class=\"company\">\n                        <\/p>\n          <\/div>\n                  <\/div>\n    <div class=\"buttons-container\">\n      <div class=\"swiper-button-left\"><\/div>\n      <div class=\"swiper-button-right\"><\/div>\n    <\/div>\n  <\/div>\n  <div class=\"dots-graphic\" ><svg width=\"154\" height=\"92\" viewBox=\"0 0 154 92\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M63 88.1872C63 87.4948 63.2057 86.818 63.5909 86.2425C63.9761 85.667 64.5236 85.2187 65.164 84.9544C65.8044 84.6901 66.5089 84.6217 67.1883 84.7579C67.8676 84.894 68.4911 85.2285 68.98 85.7191C69.4689 86.2098 69.8011 86.8343 69.9345 87.5138C70.0679 88.1932 69.9965 88.897 69.7294 89.5358C69.4622 90.1747 69.0113 90.7199 68.4338 91.1024C67.8563 91.485 67.1782 91.6877 66.4854 91.6848C65.5596 91.6809 64.6731 91.3107 64.0199 90.6552C63.3667 89.9997 63 89.1123 63 88.1872Z\" fill=\"#98B8FF\"\/>\n<path d=\"M42 88.1872C42 87.4948 42.2056 86.818 42.5908 86.2425C42.9761 85.667 43.5236 85.2187 44.164 84.9544C44.8044 84.6901 45.5089 84.6217 46.1882 84.7579C46.8675 84.894 47.4911 85.2285 47.98 85.7191C48.4689 86.2098 48.8011 86.8343 48.9345 87.5138C49.0679 88.1932 48.9965 88.897 48.7293 89.5358C48.4622 90.1747 48.0113 90.7199 47.4338 91.1024C46.8563 91.485 46.1782 91.6877 45.4854 91.6848C45.0264 91.6848 44.572 91.5942 44.1481 91.4183C43.7243 91.2423 43.3395 90.9844 43.0157 90.6595C42.6918 90.3345 42.4354 89.9487 42.2611 89.5245C42.0868 89.1002 41.9981 88.6458 42 88.1872Z\" fill=\"#98B8FF\"\/>\n<path d=\"M21 88.1872C21 87.4955 21.2052 86.8192 21.5898 86.244C21.9744 85.6689 22.521 85.2206 23.1605 84.9559C23.8001 84.6911 24.5039 84.6218 25.1828 84.7568C25.8618 84.8917 26.4854 85.2249 26.9749 85.714C27.4643 86.2032 27.7977 86.8263 27.9328 87.5048C28.0678 88.1833 27.9984 88.8866 27.7335 89.5257C27.4686 90.1648 27.02 90.711 26.4445 91.0953C25.8689 91.4796 25.1922 91.6848 24.4999 91.6848C23.5717 91.6848 22.6815 91.3162 22.0251 90.6603C21.3687 90.0044 21 89.1148 21 88.1872Z\" fill=\"#98B8FF\"\/>\n<path d=\"M-1.45956e-07 88.187C-1.74823e-07 87.4952 0.205334 86.819 0.589916 86.2438C0.974497 85.6686 1.52108 85.2203 2.16061 84.9556C2.80015 84.6909 3.50393 84.6216 4.18286 84.7565C4.86179 84.8915 5.48539 85.2246 5.97487 85.7138C6.46434 86.2029 6.79772 86.8261 6.93276 87.5046C7.06781 88.183 6.99844 88.8863 6.73353 89.5254C6.46863 90.1645 6.02004 90.7107 5.44448 91.0951C4.86891 91.4794 4.19222 91.6846 3.49999 91.6846C2.57174 91.6846 1.68157 91.316 1.0252 90.6601C0.368831 90.0041 -1.07246e-07 89.1146 -1.45956e-07 88.187Z\" fill=\"#98B8FF\"\/>\n<path d=\"M63 67.216C62.9971 66.523 63.2003 65.8447 63.5838 65.2673C63.9673 64.6899 64.5137 64.2393 65.1539 63.9727C65.794 63.7062 66.499 63.6358 67.1793 63.7703C67.8595 63.9047 68.4845 64.2381 68.9748 64.7281C69.4652 65.2182 69.7989 65.8428 69.9335 66.5226C70.068 67.2024 69.9975 67.9069 69.7307 68.5466C69.464 69.1863 69.0131 69.7324 68.4353 70.1156C67.8575 70.4988 67.1789 70.7018 66.4854 70.6989C65.5622 70.6951 64.6779 70.3269 64.0252 69.6745C63.3724 69.0222 63.0039 68.1385 63 67.216Z\" fill=\"#98B8FF\"\/>\n<path d=\"M42 67.216C41.9971 66.523 42.2003 65.8447 42.5838 65.2673C42.9673 64.6899 43.5137 64.2393 44.1539 63.9727C44.794 63.7062 45.4989 63.6358 46.1792 63.7703C46.8595 63.9047 47.4845 64.2381 47.9749 64.7281C48.4653 65.2182 48.7989 65.8428 48.9334 66.5226C49.068 67.2024 48.9975 67.9069 48.7308 68.5466C48.4641 69.1863 48.0132 69.7324 47.4354 70.1156C46.8576 70.4988 46.1789 70.7018 45.4854 70.6989C44.561 70.6989 43.6745 70.3319 43.0209 69.6787C42.3672 69.0255 42 68.1397 42 67.216Z\" fill=\"#98B8FF\"\/>\n<path d=\"M21 67.216C20.9971 66.5236 21.1999 65.8459 21.5827 65.2688C21.9655 64.6917 22.5111 64.2411 23.1504 63.9742C23.7897 63.7072 24.4939 63.6359 25.1738 63.7692C25.8537 63.9025 26.4788 64.2344 26.9697 64.723C27.4607 65.2115 27.7954 65.8347 27.9317 66.5136C28.0679 67.1924 27.9995 67.8965 27.735 68.5364C27.4705 69.1764 27.0219 69.7235 26.446 70.1085C25.8701 70.4934 25.1928 70.699 24.5 70.699C23.5743 70.699 22.6862 70.3324 22.0303 69.6796C21.3743 69.0269 21.0039 68.1411 21 67.216Z\" fill=\"#98B8FF\"\/>\n<path d=\"M3.04981e-05 67.216C-0.0028685 66.5236 0.199982 65.8459 0.582798 65.2688C0.965614 64.6917 1.51118 64.2411 2.15046 63.9742C2.78974 63.7072 3.49399 63.6359 4.17388 63.7692C4.85377 63.9025 5.47879 64.2344 5.96973 64.723C6.46068 65.2115 6.79542 65.8347 6.93166 66.5136C7.0679 67.1924 6.99949 67.8965 6.73502 68.5364C6.47055 69.1764 6.02193 69.7235 5.44605 70.1085C4.87016 70.4934 4.19288 70.699 3.50003 70.699C2.57431 70.699 1.68629 70.3324 1.03033 69.6796C0.374377 69.0269 0.00390384 68.1411 3.04981e-05 67.216Z\" fill=\"#98B8FF\"\/>\n<path d=\"M63 46.2301C62.9971 45.5371 63.2003 44.8589 63.5838 44.2814C63.9673 43.704 64.5137 43.2534 65.1539 42.9869C65.794 42.7204 66.499 42.6499 67.1793 42.7844C67.8595 42.9189 68.4845 43.2523 68.9748 43.7423C69.4652 44.2323 69.7989 44.8569 69.9335 45.5368C70.068 46.2166 69.9975 46.921 69.7307 47.5607C69.464 48.2004 69.0131 48.7465 68.4353 49.1297C67.8575 49.513 67.1789 49.716 66.4854 49.7131C65.5622 49.7093 64.6779 49.3411 64.0252 48.6888C63.3724 48.0364 63.0039 47.1527 63 46.2301Z\" fill=\"#98B8FF\"\/>\n<path d=\"M42 46.2301C41.9971 45.5371 42.2003 44.8589 42.5838 44.2814C42.9673 43.704 43.5137 43.2534 44.1539 42.9869C44.794 42.7204 45.4989 42.6499 46.1792 42.7844C46.8595 42.9189 47.4845 43.2523 47.9749 43.7423C48.4653 44.2323 48.7989 44.8569 48.9334 45.5368C49.068 46.2166 48.9975 46.921 48.7308 47.5607C48.4641 48.2004 48.0132 48.7465 47.4354 49.1297C46.8576 49.513 46.1789 49.716 45.4854 49.7131C44.561 49.7131 43.6745 49.3462 43.0209 48.693C42.3672 48.0398 42 47.1538 42 46.2301Z\" fill=\"#98B8FF\"\/>\n<path d=\"M21 46.2301C20.9971 45.5378 21.1999 44.8601 21.5827 44.283C21.9655 43.7059 22.5111 43.2554 23.1504 42.9884C23.7897 42.7214 24.4939 42.65 25.1738 42.7833C25.8537 42.9166 26.4788 43.2486 26.9697 43.7372C27.4607 44.2257 27.7954 44.8489 27.9317 45.5278C28.0679 46.2067 27.9995 46.9107 27.735 47.5507C27.4705 48.1906 27.0219 48.7377 26.446 49.1227C25.8701 49.5077 25.1928 49.7131 24.5 49.7131C23.5743 49.7131 22.6862 49.3467 22.0303 48.6939C21.3743 48.0411 21.0039 47.1552 21 46.2301Z\" fill=\"#98B8FF\"\/>\n<path d=\"M3.04981e-05 46.2301C-0.0028685 45.5378 0.199982 44.8601 0.582798 44.283C0.965614 43.7059 1.51118 43.2554 2.15046 42.9884C2.78974 42.7214 3.49399 42.65 4.17388 42.7833C4.85377 42.9166 5.47879 43.2486 5.96973 43.7372C6.46068 44.2257 6.79542 44.8489 6.93166 45.5278C7.0679 46.2067 6.99949 46.9107 6.73502 47.5507C6.47055 48.1906 6.02193 48.7377 5.44605 49.1227C4.87016 49.5077 4.19288 49.7131 3.50003 49.7131C2.57431 49.7131 1.68629 49.3467 1.03033 48.6939C0.374377 48.0411 0.00390384 47.1552 3.04981e-05 46.2301Z\" fill=\"#98B8FF\"\/>\n<path d=\"M63 25.1686C63 24.4762 63.2057 23.7994 63.5909 23.2239C63.9761 22.6484 64.5236 22.2001 65.164 21.9358C65.8044 21.6715 66.5089 21.6032 67.1883 21.7393C67.8676 21.8755 68.4911 22.21 68.98 22.7006C69.4689 23.1912 69.8011 23.8158 69.9345 24.4953C70.0679 25.1747 69.9965 25.8784 69.7294 26.5172C69.4622 27.1561 69.0113 27.7014 68.4338 28.0839C67.8563 28.4665 67.1782 28.6691 66.4854 28.6662C65.5596 28.6624 64.6731 28.2921 64.0199 27.6366C63.3667 26.9811 63 26.0937 63 25.1686Z\" fill=\"#98B8FF\"\/>\n<path d=\"M42 25.1686C42 24.4762 42.2056 23.7994 42.5908 23.2239C42.9761 22.6484 43.5236 22.2001 44.164 21.9358C44.8044 21.6715 45.5089 21.6032 46.1882 21.7393C46.8675 21.8755 47.4911 22.21 47.98 22.7006C48.4689 23.1912 48.8011 23.8158 48.9345 24.4953C49.0679 25.1747 48.9965 25.8784 48.7293 26.5172C48.4622 27.1561 48.0113 27.7014 47.4338 28.0839C46.8563 28.4665 46.1782 28.6691 45.4854 28.6662C45.0264 28.6662 44.572 28.5756 44.1481 28.3997C43.7243 28.2237 43.3395 27.9659 43.0157 27.6409C42.6918 27.3159 42.4354 26.9303 42.2611 26.506C42.0868 26.0817 41.9981 25.6272 42 25.1686Z\" fill=\"#98B8FF\"\/>\n<path d=\"M21 25.1686C21 24.4769 21.2052 23.8007 21.5898 23.2255C21.9744 22.6503 22.521 22.202 23.1605 21.9372C23.8001 21.6725 24.5039 21.6033 25.1828 21.7382C25.8618 21.8732 26.4854 22.2063 26.9749 22.6955C27.4643 23.1846 27.7977 23.8078 27.9328 24.4863C28.0678 25.1648 27.9984 25.868 27.7335 26.5071C27.4686 27.1462 27.02 27.6925 26.4445 28.0768C25.8689 28.4612 25.1922 28.6663 24.4999 28.6663C23.5717 28.6663 22.6815 28.2978 22.0251 27.6418C21.3687 26.9859 21 26.0962 21 25.1686Z\" fill=\"#98B8FF\"\/>\n<path d=\"M-1.45958e-07 25.1684C-1.74825e-07 24.4766 0.205334 23.8005 0.589916 23.2253C0.974497 22.6501 1.52108 22.2017 2.16061 21.937C2.80015 21.6723 3.50393 21.603 4.18286 21.738C4.86179 21.873 5.48539 22.2061 5.97487 22.6953C6.46434 23.1844 6.79772 23.8076 6.93276 24.4861C7.06781 25.1645 6.99844 25.8677 6.73353 26.5069C6.46863 27.146 6.02004 27.6923 5.44448 28.0766C4.86891 28.4609 4.19222 28.666 3.49999 28.666C2.57174 28.666 1.68157 28.2975 1.0252 27.6416C0.368831 26.9857 -1.07247e-07 26.096 -1.45958e-07 25.1684Z\" fill=\"#98B8FF\"\/>\n<path d=\"M63 4.18252C63 3.49013 63.2057 2.81331 63.5909 2.23782C63.9762 1.66233 64.5237 1.2141 65.164 0.949811C65.8044 0.685521 66.5089 0.61707 67.1883 0.753216C67.8676 0.889362 68.4911 1.22396 68.98 1.71458C69.4689 2.20519 69.8011 2.82978 69.9345 3.50921C70.0679 4.18864 69.9965 4.89233 69.7294 5.53117C69.4622 6.17002 69.0113 6.7153 68.4338 7.09786C67.8563 7.48042 67.1782 7.68304 66.4854 7.68014C66.0264 7.68015 65.572 7.58956 65.1482 7.41361C64.7244 7.23766 64.3395 6.97981 64.0157 6.65483C63.6918 6.32985 63.4354 5.94418 63.2611 5.51992C63.0868 5.09565 62.9981 4.64114 63 4.18252Z\" fill=\"#98B8FF\"\/>\n<path d=\"M42.0001 4.18251C42.0001 3.49013 42.2057 2.81331 42.5909 2.23782C42.9762 1.66233 43.5236 1.2141 44.164 0.949811C44.8044 0.685521 45.5089 0.61707 46.1882 0.753216C46.8675 0.889362 47.4912 1.22396 47.98 1.71458C48.4689 2.20519 48.8011 2.82978 48.9345 3.50921C49.0679 4.18864 48.9965 4.89233 48.7293 5.53117C48.4622 6.17002 48.0113 6.7153 47.4338 7.09786C46.8564 7.48042 46.1783 7.68304 45.4854 7.68014C45.026 7.6821 44.5706 7.59289 44.1459 7.41763C43.7212 7.24237 43.3356 6.98457 43.0114 6.65921C42.6872 6.33384 42.4308 5.94738 42.2572 5.52224C42.0836 5.0971 41.9962 4.64167 42.0001 4.18251Z\" fill=\"#98B8FF\"\/>\n<path d=\"M21 4.18252C21 3.49076 21.2053 2.81453 21.5899 2.23935C21.9744 1.66417 22.521 1.21589 23.1606 0.951163C23.8001 0.686438 24.5039 0.617201 25.1828 0.752157C25.8618 0.887112 26.4854 1.22026 26.9749 1.70941C27.4643 2.19856 27.7977 2.82173 27.9328 3.5002C28.0678 4.17867 27.9984 4.88189 27.7335 5.52099C27.4686 6.1601 27.02 6.7064 26.4445 7.09072C25.8689 7.47504 25.1922 7.68014 24.5 7.68014C24.0398 7.68208 23.5839 7.59289 23.1583 7.41781C22.7328 7.24272 22.3462 6.98518 22.0208 6.66001C21.6954 6.33484 21.4377 5.94854 21.2625 5.52332C21.0873 5.09809 20.9981 4.64238 21 4.18252Z\" fill=\"#98B8FF\"\/>\n<path d=\"M3.07385e-05 4.18228C3.07096e-05 3.49052 0.205364 2.81428 0.589944 2.2391C0.974524 1.66393 1.5211 1.21564 2.16063 0.950919C2.80017 0.686194 3.50395 0.616957 4.18287 0.751912C4.8618 0.886868 5.48539 1.22001 5.97487 1.70916C6.46435 2.19831 6.79772 2.82149 6.93276 3.49996C7.06781 4.17842 6.99844 4.88165 6.73353 5.52075C6.46863 6.15985 6.02005 6.70615 5.44448 7.09047C4.86892 7.47479 4.19223 7.6799 3.5 7.6799C3.03984 7.68184 2.58391 7.59265 2.1584 7.41757C1.73289 7.24248 1.34624 6.98494 1.02085 6.65977C0.695462 6.3346 0.437745 5.94829 0.262542 5.52307C0.0873394 5.09785 -0.0019068 4.64213 3.07385e-05 4.18228Z\" fill=\"#98B8FF\"\/>\n<path d=\"M84 88.1872C84 87.4955 84.2052 86.8192 84.5898 86.244C84.9744 85.6689 85.5211 85.2206 86.1606 84.9559C86.8002 84.6911 87.5039 84.6218 88.1828 84.7568C88.8617 84.8917 89.4853 85.2249 89.9748 85.714C90.4643 86.2032 90.7977 86.8263 90.9327 87.5048C91.0678 88.1833 90.9985 88.8866 90.7336 89.5257C90.4687 90.1648 90.0201 90.711 89.4445 91.0953C88.869 91.4796 88.1923 91.6848 87.5 91.6848C86.5718 91.6848 85.6815 91.3162 85.0251 90.6603C84.3687 90.0044 84 89.1148 84 88.1872Z\" fill=\"#98B8FF\"\/>\n<path d=\"M84 67.216C83.9971 66.5236 84.1999 65.8459 84.5827 65.2688C84.9655 64.6917 85.5112 64.2411 86.1505 63.9742C86.7897 63.7072 87.4939 63.6359 88.1738 63.7692C88.8537 63.9025 89.4787 64.2344 89.9697 64.723C90.4606 65.2115 90.7954 65.8347 90.9317 66.5136C91.0679 67.1924 90.9994 67.8965 90.735 68.5364C90.4705 69.1764 90.0219 69.7235 89.4461 70.1085C88.8702 70.4934 88.1929 70.699 87.5 70.699C86.5743 70.699 85.6863 70.3324 85.0303 69.6796C84.3744 69.0269 84.0039 68.1411 84 67.216Z\" fill=\"#98B8FF\"\/>\n<path d=\"M84 46.2301C83.9971 45.5378 84.1999 44.8601 84.5827 44.283C84.9655 43.7059 85.5112 43.2554 86.1505 42.9884C86.7897 42.7214 87.4939 42.65 88.1738 42.7833C88.8537 42.9166 89.4787 43.2486 89.9697 43.7372C90.4606 44.2257 90.7954 44.8489 90.9317 45.5278C91.0679 46.2067 90.9994 46.9107 90.735 47.5507C90.4705 48.1906 90.0219 48.7377 89.4461 49.1227C88.8702 49.5077 88.1929 49.7131 87.5 49.7131C86.5743 49.7131 85.6863 49.3467 85.0303 48.6939C84.3744 48.0411 84.0039 47.1552 84 46.2301Z\" fill=\"#98B8FF\"\/>\n<path d=\"M84 25.1686C84 24.4769 84.2052 23.8007 84.5898 23.2255C84.9744 22.6503 85.5211 22.202 86.1606 21.9372C86.8002 21.6725 87.5039 21.6033 88.1828 21.7382C88.8617 21.8732 89.4853 22.2063 89.9748 22.6955C90.4643 23.1846 90.7977 23.8078 90.9327 24.4863C91.0678 25.1648 90.9985 25.868 90.7336 26.5071C90.4687 27.1462 90.0201 27.6925 89.4445 28.0768C88.869 28.4612 88.1923 28.6663 87.5 28.6663C86.5718 28.6663 85.6815 28.2978 85.0251 27.6418C84.3687 26.9859 84 26.0962 84 25.1686Z\" fill=\"#98B8FF\"\/>\n<path d=\"M84 4.18252C84 3.49076 84.2053 2.81453 84.5899 2.23935C84.9744 1.66417 85.5211 1.21589 86.1607 0.951163C86.8002 0.686438 87.5039 0.617201 88.1828 0.752157C88.8618 0.887112 89.4854 1.22026 89.9748 1.70941C90.4643 2.19856 90.7977 2.82173 90.9327 3.5002C91.0678 4.17867 90.9985 4.88189 90.7336 5.52099C90.4687 6.1601 90.0201 6.7064 89.4445 7.09072C88.869 7.47504 88.1923 7.68014 87.5 7.68014C87.0399 7.68208 86.5838 7.59289 86.1583 7.41781C85.7328 7.24272 85.3462 6.98518 85.0209 6.66001C84.6955 6.33484 84.4377 5.94854 84.2625 5.52332C84.0873 5.09809 83.9981 4.64238 84 4.18252Z\" fill=\"#98B8FF\"\/>\n<path d=\"M105 88.1872C105 87.4955 105.205 86.8192 105.59 86.244C105.974 85.6689 106.521 85.2206 107.161 84.9559C107.8 84.6911 108.504 84.6218 109.183 84.7568C109.862 84.8917 110.485 85.2249 110.975 85.714C111.464 86.2032 111.798 86.8263 111.933 87.5048C112.068 88.1833 111.999 88.8866 111.734 89.5257C111.469 90.1648 111.02 90.711 110.445 91.0953C109.869 91.4796 109.192 91.6848 108.5 91.6848C107.572 91.6848 106.682 91.3162 106.025 90.6603C105.369 90.0044 105 89.1148 105 88.1872Z\" fill=\"#98B8FF\"\/>\n<path d=\"M105 67.216C104.997 66.5236 105.2 65.8459 105.583 65.2688C105.966 64.6917 106.511 64.2411 107.15 63.9742C107.79 63.7072 108.494 63.6359 109.174 63.7692C109.854 63.9025 110.479 64.2344 110.97 64.723C111.461 65.2115 111.795 65.8347 111.932 66.5136C112.068 67.1924 111.999 67.8965 111.735 68.5364C111.47 69.1764 111.022 69.7235 110.446 70.1085C109.87 70.4934 109.193 70.699 108.5 70.699C107.574 70.699 106.686 70.3324 106.03 69.6796C105.374 69.0269 105.004 68.1411 105 67.216Z\" fill=\"#98B8FF\"\/>\n<path d=\"M105 46.2301C104.997 45.5378 105.2 44.8601 105.583 44.283C105.966 43.7059 106.511 43.2554 107.15 42.9884C107.79 42.7214 108.494 42.65 109.174 42.7833C109.854 42.9166 110.479 43.2486 110.97 43.7372C111.461 44.2257 111.795 44.8489 111.932 45.5278C112.068 46.2067 111.999 46.9107 111.735 47.5507C111.47 48.1906 111.022 48.7377 110.446 49.1227C109.87 49.5077 109.193 49.7131 108.5 49.7131C107.574 49.7131 106.686 49.3467 106.03 48.6939C105.374 48.0411 105.004 47.1552 105 46.2301Z\" fill=\"#98B8FF\"\/>\n<path d=\"M105 25.1686C105 24.4769 105.205 23.8007 105.59 23.2255C105.974 22.6503 106.521 22.202 107.161 21.9372C107.8 21.6725 108.504 21.6033 109.183 21.7382C109.862 21.8732 110.485 22.2063 110.975 22.6955C111.464 23.1846 111.798 23.8078 111.933 24.4863C112.068 25.1648 111.999 25.868 111.734 26.5071C111.469 27.1462 111.02 27.6925 110.445 28.0768C109.869 28.4612 109.192 28.6663 108.5 28.6663C107.572 28.6663 106.682 28.2978 106.025 27.6418C105.369 26.9859 105 26.0962 105 25.1686Z\" fill=\"#98B8FF\"\/>\n<path d=\"M105 4.18252C105 3.49076 105.205 2.81453 105.59 2.23935C105.974 1.66417 106.521 1.21589 107.161 0.951163C107.8 0.686438 108.504 0.617201 109.183 0.752157C109.862 0.887112 110.485 1.22026 110.975 1.70941C111.464 2.19856 111.798 2.82173 111.933 3.5002C112.068 4.17867 111.999 4.88189 111.734 5.52099C111.469 6.1601 111.02 6.7064 110.445 7.09072C109.869 7.47504 109.192 7.68014 108.5 7.68014C108.04 7.68208 107.584 7.59289 107.158 7.41781C106.733 7.24272 106.346 6.98518 106.021 6.66001C105.695 6.33484 105.438 5.94854 105.263 5.52332C105.087 5.09809 104.998 4.64238 105 4.18252Z\" fill=\"#98B8FF\"\/>\n<path d=\"M126 88.1872C126 87.4955 126.205 86.8192 126.59 86.244C126.975 85.6689 127.521 85.2206 128.161 84.9559C128.8 84.6911 129.504 84.6218 130.183 84.7568C130.862 84.8917 131.485 85.2249 131.975 85.714C132.464 86.2032 132.798 86.8263 132.933 87.5048C133.068 88.1833 132.999 88.8866 132.734 89.5257C132.469 90.1648 132.02 90.711 131.445 91.0953C130.869 91.4796 130.192 91.6848 129.5 91.6848C128.572 91.6848 127.682 91.3162 127.025 90.6603C126.369 90.0044 126 89.1148 126 88.1872Z\" fill=\"#98B8FF\"\/>\n<path d=\"M126 67.216C125.997 66.5236 126.2 65.8459 126.583 65.2688C126.966 64.6917 127.511 64.2411 128.15 63.9742C128.79 63.7072 129.494 63.6359 130.174 63.7692C130.854 63.9025 131.479 64.2344 131.97 64.723C132.461 65.2115 132.795 65.8347 132.932 66.5136C133.068 67.1924 132.999 67.8965 132.735 68.5364C132.471 69.1764 132.022 69.7235 131.446 70.1085C130.87 70.4934 130.193 70.699 129.5 70.699C128.574 70.699 127.686 70.3324 127.03 69.6796C126.374 69.0269 126.004 68.1411 126 67.216Z\" fill=\"#98B8FF\"\/>\n<path d=\"M126 46.2301C125.997 45.5378 126.2 44.8601 126.583 44.283C126.966 43.7059 127.511 43.2554 128.15 42.9884C128.79 42.7214 129.494 42.65 130.174 42.7833C130.854 42.9166 131.479 43.2486 131.97 43.7372C132.461 44.2257 132.795 44.8489 132.932 45.5278C133.068 46.2067 132.999 46.9107 132.735 47.5507C132.471 48.1906 132.022 48.7377 131.446 49.1227C130.87 49.5077 130.193 49.7131 129.5 49.7131C128.574 49.7131 127.686 49.3467 127.03 48.6939C126.374 48.0411 126.004 47.1552 126 46.2301Z\" fill=\"#98B8FF\"\/>\n<path d=\"M126 25.1686C126 24.4769 126.205 23.8007 126.59 23.2255C126.975 22.6503 127.521 22.202 128.161 21.9372C128.8 21.6725 129.504 21.6033 130.183 21.7382C130.862 21.8732 131.485 22.2063 131.975 22.6955C132.464 23.1846 132.798 23.8078 132.933 24.4863C133.068 25.1648 132.999 25.868 132.734 26.5071C132.469 27.1462 132.02 27.6925 131.445 28.0768C130.869 28.4612 130.192 28.6663 129.5 28.6663C128.572 28.6663 127.682 28.2978 127.025 27.6418C126.369 26.9859 126 26.0962 126 25.1686Z\" fill=\"#98B8FF\"\/>\n<path d=\"M126 4.18252C126 3.49076 126.205 2.81453 126.59 2.23935C126.975 1.66417 127.521 1.21589 128.161 0.951163C128.8 0.686438 129.504 0.617201 130.183 0.752157C130.862 0.887112 131.485 1.22026 131.975 1.70941C132.464 2.19856 132.798 2.82173 132.933 3.5002C133.068 4.17867 132.999 4.88189 132.734 5.52099C132.469 6.1601 132.02 6.7064 131.445 7.09072C130.869 7.47504 130.192 7.68014 129.5 7.68014C129.04 7.68208 128.584 7.59289 128.158 7.41781C127.733 7.24272 127.346 6.98518 127.021 6.66001C126.695 6.33484 126.438 5.94854 126.263 5.52332C126.087 5.09809 125.998 4.64238 126 4.18252Z\" fill=\"#98B8FF\"\/>\n<path d=\"M147 88.1872C147 87.4948 147.206 86.818 147.591 86.2425C147.976 85.667 148.524 85.2187 149.164 84.9544C149.804 84.6901 150.509 84.6217 151.188 84.7579C151.868 84.894 152.491 85.2285 152.98 85.7191C153.469 86.2098 153.801 86.8343 153.935 87.5138C154.068 88.1932 153.997 88.897 153.729 89.5358C153.462 90.1747 153.011 90.7199 152.434 91.1024C151.856 91.485 151.178 91.6877 150.485 91.6848C150.026 91.6848 149.572 91.5942 149.148 91.4183C148.724 91.2423 148.34 90.9844 148.016 90.6595C147.692 90.3345 147.435 89.9487 147.261 89.5245C147.087 89.1002 146.998 88.6458 147 88.1872Z\" fill=\"#98B8FF\"\/>\n<path d=\"M147 67.216C146.997 66.523 147.2 65.8447 147.584 65.2673C147.967 64.6899 148.514 64.2393 149.154 63.9727C149.794 63.7062 150.499 63.6358 151.179 63.7703C151.86 63.9047 152.484 64.2381 152.975 64.7281C153.465 65.2182 153.799 65.8428 153.933 66.5226C154.068 67.2024 153.997 67.9069 153.731 68.5466C153.464 69.1863 153.013 69.7324 152.435 70.1156C151.858 70.4988 151.179 70.7018 150.485 70.6989C149.561 70.6989 148.674 70.3319 148.021 69.6787C147.367 69.0255 147 68.1397 147 67.216Z\" fill=\"#98B8FF\"\/>\n<path d=\"M147.001 46.2273C146.986 45.532 147.179 44.8482 147.556 44.2632C147.932 43.6781 148.474 43.2185 149.113 42.9429C149.752 42.6674 150.459 42.5884 151.143 42.7161C151.827 42.8439 152.458 43.1726 152.954 43.6602C153.45 44.1478 153.79 44.7721 153.929 45.4535C154.068 46.1348 154.001 46.8423 153.737 47.4854C153.472 48.1286 153.021 48.6782 152.442 49.0641C151.863 49.45 151.182 49.6546 150.486 49.6518C149.562 49.6518 148.675 49.2849 148.022 48.6317C147.368 47.9785 147.001 47.0926 147.001 46.1688\" fill=\"#98B8FF\"\/>\n<path d=\"M147 25.1686C147 24.4762 147.206 23.7994 147.591 23.2239C147.976 22.6484 148.524 22.2001 149.164 21.9358C149.804 21.6715 150.509 21.6032 151.188 21.7393C151.868 21.8755 152.491 22.21 152.98 22.7006C153.469 23.1912 153.801 23.8158 153.935 24.4953C154.068 25.1747 153.997 25.8784 153.729 26.5172C153.462 27.1561 153.011 27.7014 152.434 28.0839C151.856 28.4665 151.178 28.6691 150.485 28.6662C150.026 28.6662 149.572 28.5756 149.148 28.3997C148.724 28.2237 148.34 27.9659 148.016 27.6409C147.692 27.3159 147.435 26.9303 147.261 26.506C147.087 26.0817 146.998 25.6272 147 25.1686Z\" fill=\"#98B8FF\"\/>\n<path d=\"M147 4.18251C147 3.49013 147.206 2.81331 147.591 2.23782C147.976 1.66233 148.524 1.2141 149.164 0.949811C149.804 0.685521 150.509 0.61707 151.188 0.753216C151.868 0.889362 152.491 1.22396 152.98 1.71458C153.469 2.20519 153.801 2.82978 153.935 3.50921C154.068 4.18864 153.997 4.89233 153.729 5.53117C153.462 6.17002 153.011 6.7153 152.434 7.09786C151.856 7.48042 151.178 7.68304 150.485 7.68014C150.026 7.6821 149.571 7.59289 149.146 7.41763C148.721 7.24237 148.336 6.98457 148.011 6.65921C147.687 6.33384 147.431 5.94738 147.257 5.52224C147.084 5.0971 146.996 4.64167 147 4.18251Z\" fill=\"#98B8FF\"\/>\n<\/svg>\n<\/div>\n<\/section>\n\n\n<script>\n  const swiper = new Swiper('.swiper', {\n    direction: 'horizontal',\n    loop: true,\n    pagination: {\n      el: '.swiper-pagination',\n    },\n    navigation: {\n      nextEl: '.swiper-button-right',\n      prevEl: '.swiper-button-left',\n    },\n    scrollbar: {\n      el: '.swiper-scrollbar',\n    },\n  });\n<\/script>\n\n\n<section class=\"news-section\">\n    <h2>\n        Zi\u0146as    <\/h2>\n    <div class=\"news-wrapper\">\n                                    <article class=\"news-post\">\n                    <figure>\n                        <img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"524\" src=\"https:\/\/werkado.eu\/wp-content\/uploads\/2024\/07\/232398.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/werkado.eu\/wp-content\/uploads\/2024\/07\/232398.jpg 700w, https:\/\/werkado.eu\/wp-content\/uploads\/2024\/07\/232398-300x225.jpg 300w, https:\/\/werkado.eu\/wp-content\/uploads\/2024\/07\/232398-65x49.jpg 65w, https:\/\/werkado.eu\/wp-content\/uploads\/2024\/07\/232398-53x40.jpg 53w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/>                    <\/figure>\n                    <h6 class=\"news-title\">\n                        Right to Repair &#8211; ties\u012bbas uz remontu                    <\/h6>\n                    <div class=\"news-author-wrapper\">\n                        <p class=\"news-date body1\">\n                            29.07.2024                        <\/p>\n                        <p class=\"news-author body1\">\n                            kert                        <\/p>\n                    <\/div>\n                    <!-- <p class=\"news-excerpt\">\n                                <p>Kas ir Eiropas Direkt\u012bva par Ties\u012bb\u0101m uz Remontu? K\u0101 eiropie\u0161i, m\u0113s esam pieradu\u0161i pie ties\u012bb\u0101m pie\u0146emt l\u0113mumus. Mums ir izv\u0113les iesp\u0113jas gandr\u012bz vis\u0101 \u2013 \u0113dien\u0101, m\u0101jokl\u012b, darb\u0101 un draugos. M\u0113s varam ar\u012b izv\u0113l\u0113ties, cik daudz un uz ko m\u0113s t\u0113r\u0113jam, cik p\u0101rdom\u0101ti m\u0113s veicam pirkuma l\u0113mumus un ko m\u0113s visp\u0101r pat\u0113r\u0113jam. K\u0101 saka \u2013 j\u016bs [&hellip;]<\/p>\n                            <\/p> -->\n                    <a href=\"https:\/\/werkado.eu\/lv\/?post_type=post&#038;p=5354\">\n                        Las\u012bt vair\u0101k                    <\/a>\n                <\/article>\n                            <article class=\"news-post\">\n                    <figure>\n                        <img loading=\"lazy\" decoding=\"async\" width=\"694\" height=\"550\" src=\"https:\/\/werkado.eu\/wp-content\/uploads\/2023\/10\/Mechanix-Wear-Gloves.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/werkado.eu\/wp-content\/uploads\/2023\/10\/Mechanix-Wear-Gloves.png 694w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/10\/Mechanix-Wear-Gloves-300x238.png 300w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/10\/Mechanix-Wear-Gloves-65x52.png 65w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/10\/Mechanix-Wear-Gloves-50x40.png 50w\" sizes=\"auto, (max-width: 694px) 100vw, 694px\" \/>                    <\/figure>\n                    <h6 class=\"news-title\">\n                        Sagatavosimies ziemai, izv\u0113loties sezonai piem\u0113rotus cimdus!                    <\/h6>\n                    <div class=\"news-author-wrapper\">\n                        <p class=\"news-date body1\">\n                            10.10.2023                        <\/p>\n                        <p class=\"news-author body1\">\n                            kert                        <\/p>\n                    <\/div>\n                    <!-- <p class=\"news-excerpt\">\n                                <p>Izv\u0113loties ziemas aizsargcimdus, profesion\u0101\u013ciem j\u0101\u0146em v\u0113r\u0101 vair\u0101ki faktori, lai tie nodro\u0161in\u0101tu pietiekamu siltumu, komfortu un dro\u0161\u012bbu aukstum\u0101. Apl\u016bkosim piecas lietas, kas j\u0101\u0146em v\u0113r\u0101, un izplat\u012bt\u0101k\u0101s k\u013c\u016bdas, no kur\u0101m j\u0101izvair\u0101s. Lietas, kas j\u0101\u0146em v\u0113r\u0101, izv\u0113loties ide\u0101lus ziemas cimdus darbam \u0101r\u0101 Izol\u0101cija un siltums: \u016adens un v\u0113ja necaurlaid\u012bbas \u012bpa\u0161\u012bbas: Izveic\u012bba un satv\u0113riens: Iztur\u012bba un aizsardz\u012bba: Piem\u0113rot\u012bba un [&hellip;]<\/p>\n                            <\/p> -->\n                    <a href=\"https:\/\/werkado.eu\/lv\/?post_type=post&#038;p=3927\">\n                        Las\u012bt vair\u0101k                    <\/a>\n                <\/article>\n                            <article class=\"news-post\">\n                    <figure>\n                        <img loading=\"lazy\" decoding=\"async\" width=\"2200\" height=\"1350\" src=\"https:\/\/werkado.eu\/wp-content\/uploads\/2023\/10\/Tivoly-background.webp\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/werkado.eu\/wp-content\/uploads\/2023\/10\/Tivoly-background.webp 2200w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/10\/Tivoly-background-300x184.webp 300w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/10\/Tivoly-background-1024x628.webp 1024w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/10\/Tivoly-background-768x471.webp 768w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/10\/Tivoly-background-1536x943.webp 1536w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/10\/Tivoly-background-2048x1257.webp 2048w, https:\/\/werkado.eu\/wp-content\/uploads\/2023\/10\/Tivoly-background-65x40.webp 65w\" sizes=\"auto, (max-width: 2200px) 100vw, 2200px\" \/>                    <\/figure>\n                    <h6 class=\"news-title\">\n                        Aizraujo\u0161i Tivoly urbju un fr\u0113z\u0113\u0161anas uzga\u013cu komplekti                    <\/h6>\n                    <div class=\"news-author-wrapper\">\n                        <p class=\"news-date body1\">\n                                                    <\/p>\n                        <p class=\"news-author body1\">\n                            kert                        <\/p>\n                    <\/div>\n                    <!-- <p class=\"news-excerpt\">\n                                <p>Tivoly ir fran\u010du z\u012bmols, kas visu savu produktu kl\u0101stu izstr\u0101d\u0101 un ra\u017eo uz\u0146\u0113muma ietvaros. Baltij\u0101 uz\u0146\u0113mumam Werkado ir ekskluz\u012bvas Tivoly produktu p\u0101rst\u0101v\u012bbas ties\u012bbas. Katra Tivoly kl\u0101sta komplekta rad\u012b\u0161anas pamats ir nepiecie\u0161am\u012bba, un glab\u0101\u0161anas iepakojumu izstr\u0101d\u0113 ir \u0146emts v\u0113r\u0101 ar\u012b lietot\u0101ja komforts un pre\u010du lo\u0123iskais izk\u0101rtojums. \u0160aj\u0101 rakst\u0101 iepaz\u012bstin\u0101m ar diviem m\u016bsu lielajiem favor\u012btiem, kas, iesp\u0113jams, [&hellip;]<\/p>\n                            <\/p> -->\n                    <a href=\"https:\/\/werkado.eu\/lv\/?post_type=post&#038;p=3935\">\n                        Las\u012bt vair\u0101k                    <\/a>\n                <\/article>\n                        <\/div>\n    <div class=\"center-element\">\n        <\/div>\n<\/section>\n\n\n\n\n<section class=\"contact_form-section\">\n    <article class=\"contact_form-wrapper\">\n        <div class=\"footer-cta-title\">Vai v\u0113laties uzs\u0101kt sadarb\u012bbu vai jums ir k\u0101di jaut\u0101jumi?<\/br>\n        <span class=\"dark-blue\">Sazinieties ar mums!<\/span><\/div>\n        <div class=\"contact_form-content\">\n        <div class='_form_24'><\/div><script type='text\/javascript' src='https:\/\/toolmarketing.activehosted.com\/f\/embed.php?static=0&#038;id=24&#038;6A049034A32B3&#038;nostyles=1&#038;preview=0'><\/script>        <\/div>\n    <\/article>\n    <div class=\"dots-graphic-left\" ><svg width=\"154\" height=\"93\" viewBox=\"0 0 154 93\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M90.9922 3.64683C90.9922 4.35066 90.7865 5.03868 90.4013 5.62369C90.016 6.2087 89.4686 6.66443 88.8282 6.9331C88.1878 7.20176 87.4833 7.27125 86.8039 7.13285C86.1246 6.99446 85.5011 6.65441 85.0122 6.15568C84.5233 5.65695 84.1911 5.02203 84.0577 4.33136C83.9243 3.64069 83.9957 2.92527 84.2628 2.27586C84.53 1.62645 84.9809 1.07223 85.5584 0.683347C86.1359 0.294462 86.814 0.0883954 87.5068 0.0913402C88.4325 0.0952748 89.319 0.471621 89.9723 1.13797C90.6255 1.80433 90.9922 2.70643 90.9922 3.64683Z\" fill=\"#004BD1\"\/>\n<path d=\"M111.992 3.64683C111.992 4.35066 111.787 5.03868 111.401 5.62369C111.016 6.2087 110.469 6.66443 109.828 6.9331C109.188 7.20176 108.483 7.27125 107.804 7.13285C107.125 6.99446 106.501 6.65441 106.012 6.15568C105.523 5.65695 105.191 5.02203 105.058 4.33136C104.924 3.64069 104.996 2.92527 105.263 2.27586C105.53 1.62645 105.981 1.07223 106.558 0.683347C107.136 0.294462 107.814 0.0883954 108.507 0.0913402C108.966 0.091336 109.42 0.183422 109.844 0.362283C110.268 0.541143 110.653 0.803264 110.977 1.13362C111.3 1.46397 111.557 1.85611 111.731 2.28739C111.905 2.71867 111.994 3.18062 111.992 3.64683Z\" fill=\"#004BD1\"\/>\n<path d=\"M132.992 3.64678C132.992 4.34999 132.787 5.03741 132.402 5.6221C132.018 6.20679 131.471 6.66248 130.832 6.93159C130.192 7.20069 129.488 7.27117 128.809 7.13398C128.13 6.99679 127.507 6.65813 127.017 6.16089C126.528 5.66366 126.194 5.03017 126.059 4.34048C125.924 3.65079 125.994 2.93585 126.259 2.28617C126.524 1.6365 126.972 1.08126 127.548 0.690577C128.123 0.299899 128.8 0.0913092 129.492 0.0913091C130.421 0.0913089 131.311 0.465987 131.967 1.13276C132.623 1.79954 132.992 2.70382 132.992 3.64678Z\" fill=\"#004BD1\"\/>\n<path d=\"M153.992 3.64629C153.992 4.3495 153.787 5.03692 153.402 5.62161C153.018 6.2063 152.471 6.662 151.832 6.9311C151.192 7.2002 150.488 7.27068 149.809 7.13349C149.13 6.9963 148.507 6.65765 148.017 6.16041C147.528 5.66317 147.194 5.02968 147.059 4.33999C146.924 3.6503 146.994 2.93536 147.259 2.28569C147.524 1.63601 147.972 1.08077 148.548 0.690089C149.123 0.299411 149.8 0.0908209 150.492 0.0908208C151.42 0.0908207 152.311 0.465499 152.967 1.13228C153.623 1.79905 153.992 2.70333 153.992 3.64629Z\" fill=\"#004BD1\"\/>\n<path d=\"M90.9922 24.9649C90.9951 25.6694 90.7919 26.3589 90.4084 26.9459C90.0249 27.5329 89.4785 27.9909 88.8383 28.2618C88.1982 28.5328 87.4932 28.6044 86.8129 28.4677C86.1326 28.331 85.5077 27.9921 85.0173 27.494C84.527 26.9958 84.1933 26.3609 84.0587 25.6698C83.9241 24.9787 83.9947 24.2626 84.2614 23.6123C84.5282 22.962 84.979 22.4069 85.5568 22.0174C86.1347 21.6278 86.8133 21.4214 87.5068 21.4243C88.43 21.4283 89.3142 21.8026 89.967 22.4657C90.6198 23.1289 90.9883 24.0271 90.9922 24.9649Z\" fill=\"#004BD1\"\/>\n<path d=\"M111.992 24.9654C111.995 25.6699 111.792 26.3594 111.408 26.9464C111.025 27.5333 110.478 27.9914 109.838 28.2623C109.198 28.5333 108.493 28.6049 107.813 28.4682C107.133 28.3315 106.508 27.9926 106.017 27.4944C105.527 26.9963 105.193 26.3614 105.059 25.6703C104.924 24.9792 104.995 24.2631 105.261 23.6128C105.528 22.9625 105.979 22.4074 106.557 22.0178C107.135 21.6283 107.813 21.4219 108.507 21.4248C109.431 21.4248 110.318 21.7979 110.971 22.4619C111.625 23.1259 111.992 24.0264 111.992 24.9654Z\" fill=\"#004BD1\"\/>\n<path d=\"M132.992 24.9654C132.995 25.6692 132.792 26.3582 132.409 26.9448C132.027 27.5315 131.481 27.9895 130.842 28.2609C130.203 28.5323 129.498 28.6048 128.818 28.4693C128.138 28.3337 127.513 27.9963 127.022 27.4997C126.532 27.0031 126.197 26.3696 126.061 25.6795C125.924 24.9894 125.993 24.2737 126.257 23.6231C126.522 22.9726 126.97 22.4164 127.546 22.0251C128.122 21.6337 128.799 21.4248 129.492 21.4248C130.418 21.4248 131.306 21.7974 131.962 22.461C132.618 23.1246 132.988 24.025 132.992 24.9654Z\" fill=\"#004BD1\"\/>\n<path d=\"M153.992 24.9649C153.995 25.6688 153.792 26.3577 153.409 26.9443C153.027 27.531 152.481 27.989 151.842 28.2604C151.202 28.5318 150.498 28.6043 149.818 28.4688C149.138 28.3333 148.513 27.9959 148.022 27.4992C147.532 27.0026 147.197 26.3691 147.061 25.679C146.924 24.9889 146.993 24.2732 147.257 23.6226C147.522 22.9721 147.97 22.4159 148.546 22.0246C149.122 21.6332 149.799 21.4243 150.492 21.4243C151.418 21.4243 152.306 21.7969 152.962 22.4605C153.618 23.1241 153.988 24.0245 153.992 24.9649Z\" fill=\"#004BD1\"\/>\n<path d=\"M91 46.299C91.0029 47.0034 90.7997 47.6929 90.4162 48.2799C90.0327 48.8668 89.4863 49.3249 88.8461 49.5958C88.206 49.8668 87.501 49.9384 86.8207 49.8017C86.1405 49.6649 85.5155 49.3261 85.0252 48.8279C84.5348 48.3298 84.2011 47.6948 84.0665 47.0038C83.932 46.3127 84.0025 45.5966 84.2693 44.9463C84.536 44.296 84.9869 43.7409 85.5647 43.3513C86.1425 42.9618 86.8211 42.7554 87.5146 42.7583C88.4378 42.7622 89.3221 43.1365 89.9748 43.7996C90.6276 44.4628 90.9961 45.3611 91 46.299Z\" fill=\"#004BD1\"\/>\n<path d=\"M112 46.299C112.003 47.0034 111.8 47.6929 111.416 48.2799C111.033 48.8668 110.486 49.3249 109.846 49.5958C109.206 49.8668 108.501 49.9384 107.821 49.8017C107.14 49.6649 106.515 49.3261 106.025 48.8279C105.535 48.3298 105.201 47.6948 105.067 47.0038C104.932 46.3127 105.002 45.5966 105.269 44.9463C105.536 44.296 105.987 43.7409 106.565 43.3513C107.142 42.9618 107.821 42.7554 108.515 42.7583C109.439 42.7583 110.325 43.1314 110.979 43.7954C111.633 44.4594 112 45.3599 112 46.299Z\" fill=\"#004BD1\"\/>\n<path d=\"M133 46.2989C133.003 47.0028 132.8 47.6916 132.417 48.2783C132.034 48.8649 131.489 49.3229 130.85 49.5943C130.21 49.8657 129.506 49.9383 128.826 49.8028C128.146 49.6673 127.521 49.3298 127.03 48.8331C126.539 48.3365 126.205 47.703 126.068 47.0129C125.932 46.3228 126.001 45.6071 126.265 44.9565C126.529 44.306 126.978 43.7498 127.554 43.3585C128.13 42.9671 128.807 42.7583 129.5 42.7583C130.426 42.7583 131.314 43.1308 131.97 43.7944C132.626 44.458 132.996 45.3585 133 46.2989Z\" fill=\"#004BD1\"\/>\n<path d=\"M154 46.2984C154.003 47.0023 153.8 47.6911 153.417 48.2778C153.034 48.8644 152.489 49.3224 151.85 49.5938C151.21 49.8652 150.506 49.9378 149.826 49.8023C149.146 49.6668 148.521 49.3293 148.03 48.8326C147.539 48.336 147.205 47.7025 147.068 47.0124C146.932 46.3223 147.001 45.6066 147.265 44.9561C147.529 44.3055 147.978 43.7493 148.554 43.358C149.13 42.9667 149.807 42.7578 150.5 42.7578C151.426 42.7578 152.314 43.1304 152.97 43.7939C153.626 44.4575 153.996 45.358 154 46.2984Z\" fill=\"#004BD1\"\/>\n<path d=\"M90.9922 67.7064C90.9922 68.4103 90.7865 69.0982 90.4013 69.6832C90.016 70.2683 89.4686 70.724 88.8282 70.9927C88.1878 71.2613 87.4833 71.3308 86.8039 71.1924C86.1246 71.054 85.5011 70.714 85.0122 70.2152C84.5233 69.7165 84.1911 69.0816 84.0577 68.3909C83.9243 67.7002 83.9957 66.9849 84.2628 66.3355C84.53 65.686 84.9809 65.1317 85.5584 64.7428C86.1359 64.3539 86.814 64.148 87.5068 64.1509C88.4325 64.1548 89.319 64.5312 89.9723 65.1976C90.6255 65.8639 90.9922 66.766 90.9922 67.7064Z\" fill=\"#004BD1\"\/>\n<path d=\"M111.992 67.7064C111.992 68.4103 111.787 69.0982 111.401 69.6832C111.016 70.2683 110.469 70.724 109.828 70.9927C109.188 71.2613 108.483 71.3308 107.804 71.1924C107.125 71.054 106.501 70.714 106.012 70.2152C105.523 69.7165 105.191 69.0816 105.058 68.3909C104.924 67.7002 104.996 66.9849 105.263 66.3355C105.53 65.686 105.981 65.1317 106.558 64.7428C107.136 64.3539 107.814 64.148 108.507 64.1509C108.966 64.1509 109.42 64.243 109.844 64.4219C110.268 64.6007 110.653 64.8628 110.977 65.1932C111.3 65.5236 111.557 65.9156 111.731 66.3469C111.905 66.7782 111.994 67.2402 111.992 67.7064Z\" fill=\"#004BD1\"\/>\n<path d=\"M132.992 67.7064C132.992 68.4096 132.787 69.0969 132.402 69.6816C132.018 70.2663 131.471 70.7221 130.832 70.9912C130.192 71.2603 129.488 71.3307 128.809 71.1935C128.13 71.0563 127.507 70.7177 127.017 70.2204C126.528 69.7232 126.194 69.0897 126.059 68.4C125.924 67.7103 125.994 66.9954 126.259 66.3458C126.524 65.6961 126.972 65.1407 127.548 64.7501C128.123 64.3594 128.8 64.1509 129.492 64.1509C130.421 64.1509 131.311 64.5255 131.967 65.1923C132.623 65.859 132.992 66.7634 132.992 67.7064Z\" fill=\"#004BD1\"\/>\n<path d=\"M153.992 67.7064C153.992 68.4096 153.787 69.0969 153.402 69.6816C153.018 70.2663 152.471 70.7221 151.832 70.9912C151.192 71.2603 150.488 71.3307 149.809 71.1935C149.13 71.0563 148.507 70.7177 148.017 70.2204C147.528 69.7232 147.194 69.0897 147.059 68.4C146.924 67.7103 146.994 66.9954 147.259 66.3458C147.524 65.6961 147.972 65.1407 148.548 64.7501C149.123 64.3594 149.8 64.1509 150.492 64.1509C151.42 64.1509 152.311 64.5255 152.967 65.1923C153.623 65.859 153.992 66.7634 153.992 67.7064Z\" fill=\"#004BD1\"\/>\n<path d=\"M91 89.0399C91 89.7437 90.7943 90.4318 90.4091 91.0168C90.0238 91.6018 89.4763 92.0574 88.836 92.3261C88.1956 92.5948 87.4911 92.6643 86.8117 92.5259C86.1324 92.3875 85.5089 92.0474 85.02 91.5487C84.5311 91.0499 84.1989 90.415 84.0655 89.7243C83.9321 89.0337 84.0035 88.3183 84.2706 87.6689C84.5378 87.0195 84.9887 86.4652 85.5662 86.0763C86.1437 85.6874 86.8218 85.4815 87.5146 85.4844C87.9736 85.4844 88.428 85.5765 88.8518 85.7554C89.2756 85.9342 89.6605 86.1963 89.9843 86.5267C90.3082 86.857 90.5646 87.2491 90.7389 87.6804C90.9132 88.1117 91.0019 88.5737 91 89.0399Z\" fill=\"#004BD1\"\/>\n<path d=\"M112 89.0399C112 89.7437 111.794 90.4318 111.409 91.0168C111.024 91.6018 110.476 92.0574 109.836 92.3261C109.196 92.5948 108.491 92.6643 107.812 92.5259C107.132 92.3875 106.509 92.0474 106.02 91.5487C105.531 91.0499 105.199 90.415 105.065 89.7243C104.932 89.0337 105.004 88.3183 105.271 87.6689C105.538 87.0195 105.989 86.4652 106.566 86.0763C107.144 85.6874 107.822 85.4815 108.515 85.4844C108.974 85.4824 109.429 85.5731 109.854 85.7513C110.279 85.9294 110.664 86.1915 110.989 86.5222C111.313 86.853 111.569 87.2458 111.743 87.678C111.916 88.1102 112.004 88.5731 112 89.0399Z\" fill=\"#004BD1\"\/>\n<path d=\"M133 89.0399C133 89.7431 132.795 90.4305 132.41 91.0152C132.026 91.5999 131.479 92.0556 130.839 92.3247C130.2 92.5938 129.496 92.6642 128.817 92.527C128.138 92.3898 127.515 92.0512 127.025 91.5539C126.536 91.0567 126.202 90.4232 126.067 89.7335C125.932 89.0438 126.002 88.329 126.266 87.6793C126.531 87.0296 126.98 86.4743 127.556 86.0836C128.131 85.6929 128.808 85.4844 129.5 85.4844C129.96 85.4824 130.416 85.5731 130.842 85.7511C131.267 85.9291 131.654 86.1909 131.979 86.5214C132.305 86.852 132.562 87.2447 132.738 87.6769C132.913 88.1092 133.002 88.5724 133 89.0399Z\" fill=\"#004BD1\"\/>\n<path d=\"M154 89.0394C154 89.7426 153.795 90.43 153.41 91.0147C153.025 91.5994 152.479 92.0551 151.839 92.3242C151.2 92.5933 150.496 92.6637 149.817 92.5265C149.138 92.3893 148.515 92.0507 148.025 91.5534C147.536 91.0562 147.202 90.4227 147.067 89.733C146.932 89.0433 147.002 88.3285 147.266 87.6788C147.531 87.0291 147.98 86.4738 148.556 86.0831C149.131 85.6924 149.808 85.4839 150.5 85.4839C150.96 85.482 151.416 85.5726 151.842 85.7506C152.267 85.9286 152.654 86.1904 152.979 86.5209C153.305 86.8515 153.562 87.2442 153.737 87.6764C153.913 88.1087 154.002 88.5719 154 89.0394Z\" fill=\"#004BD1\"\/>\n<path d=\"M70 3.64678C70 4.34999 69.7948 5.03741 69.4102 5.6221C69.0256 6.20679 68.4789 6.66248 67.8394 6.93159C67.1998 7.20069 66.4961 7.27117 65.8172 7.13398C65.1383 6.99679 64.5147 6.65813 64.0252 6.16089C63.5357 5.66366 63.2023 5.03017 63.0673 4.34048C62.9322 3.65079 63.0015 2.93585 63.2664 2.28617C63.5313 1.6365 63.9799 1.08126 64.5555 0.690577C65.131 0.299899 65.8077 0.0913092 66.5 0.0913091C67.4282 0.0913089 68.3185 0.465987 68.9749 1.13276C69.6313 1.79954 70 2.70382 70 3.64678Z\" fill=\"#004BD1\"\/>\n<path d=\"M70 24.9649C70.0029 25.6688 69.8001 26.3577 69.4173 26.9443C69.0345 27.531 68.4888 27.989 67.8495 28.2604C67.2103 28.5318 66.5061 28.6043 65.8262 28.4688C65.1463 28.3333 64.5213 27.9959 64.0303 27.4992C63.5394 27.0026 63.2046 26.3691 63.0683 25.679C62.9321 24.9889 63.0006 24.2732 63.265 23.6226C63.5295 22.9721 63.9781 22.4159 64.5539 22.0246C65.1298 21.6332 65.8071 21.4243 66.5 21.4243C67.4257 21.4243 68.3137 21.7969 68.9697 22.4605C69.6256 23.1241 69.9961 24.0245 70 24.9649Z\" fill=\"#004BD1\"\/>\n<path d=\"M70.0078 46.2989C70.0107 47.0028 69.8079 47.6916 69.4251 48.2783C69.0423 48.8649 68.4966 49.3229 67.8573 49.5943C67.2181 49.8657 66.5139 49.9383 65.834 49.8028C65.1541 49.6673 64.5291 49.3298 64.0381 48.8331C63.5472 48.3365 63.2124 47.703 63.0761 47.0129C62.9399 46.3228 63.0084 45.6071 63.2729 44.9565C63.5373 44.306 63.9859 43.7498 64.5617 43.3585C65.1376 42.9671 65.8149 42.7583 66.5078 42.7583C67.4335 42.7583 68.3215 43.1308 68.9775 43.7944C69.6334 44.458 70.0039 45.3585 70.0078 46.2989Z\" fill=\"#004BD1\"\/>\n<path d=\"M70 67.7064C70 68.4096 69.7948 69.0969 69.4102 69.6816C69.0256 70.2663 68.4789 70.7221 67.8394 70.9912C67.1998 71.2603 66.4961 71.3307 65.8172 71.1935C65.1383 71.0563 64.5147 70.7177 64.0252 70.2204C63.5357 69.7232 63.2023 69.0897 63.0673 68.4C62.9322 67.7103 63.0015 66.9954 63.2664 66.3458C63.5313 65.6961 63.9799 65.1407 64.5555 64.7501C65.131 64.3594 65.8077 64.1509 66.5 64.1509C67.4282 64.1509 68.3185 64.5255 68.9749 65.1923C69.6313 65.859 70 66.7634 70 67.7064Z\" fill=\"#004BD1\"\/>\n<path d=\"M70.0078 89.0399C70.0078 89.7431 69.8025 90.4305 69.418 91.0152C69.0334 91.5999 68.4867 92.0556 67.8472 92.3247C67.2076 92.5938 66.5039 92.6642 65.825 92.527C65.1461 92.3898 64.5225 92.0512 64.033 91.5539C63.5435 91.0567 63.2101 90.4232 63.0751 89.7335C62.94 89.0438 63.0093 88.329 63.2742 87.6793C63.5391 87.0296 63.9877 86.4743 64.5633 86.0836C65.1388 85.6929 65.8155 85.4844 66.5078 85.4844C66.9679 85.4824 67.424 85.5731 67.8495 85.7511C68.275 85.9291 68.6616 86.1909 68.987 86.5214C69.3123 86.852 69.5701 87.2447 69.7453 87.6769C69.9205 88.1092 70.0097 88.5724 70.0078 89.0399Z\" fill=\"#004BD1\"\/>\n<path d=\"M49 3.64678C49 4.34999 48.7948 5.03741 48.4102 5.6221C48.0256 6.20679 47.4789 6.66248 46.8394 6.93159C46.1998 7.20069 45.4961 7.27117 44.8172 7.13398C44.1383 6.99679 43.5146 6.65813 43.0251 6.16089C42.5356 5.66366 42.2023 5.03017 42.0673 4.34048C41.9322 3.65079 42.0015 2.93585 42.2664 2.28617C42.5313 1.6365 42.9799 1.08126 43.5555 0.690577C44.131 0.299899 44.8077 0.0913092 45.5 0.0913091C46.4282 0.0913089 47.3185 0.465987 47.9749 1.13276C48.6313 1.79954 49 2.70382 49 3.64678Z\" fill=\"#004BD1\"\/>\n<path d=\"M49 24.9654C49.0029 25.6692 48.8 26.3582 48.4172 26.9448C48.0344 27.5315 47.4888 27.9895 46.8495 28.2609C46.2103 28.5323 45.5061 28.6048 44.8262 28.4693C44.1463 28.3337 43.5213 27.9963 43.0303 27.4997C42.5394 27.0031 42.2046 26.3696 42.0683 25.6795C41.9321 24.9894 42.0006 24.2737 42.265 23.6231C42.5295 22.9726 42.9781 22.4164 43.5539 22.0251C44.1298 21.6337 44.8071 21.4248 45.5 21.4248C46.4257 21.4248 47.3137 21.7974 47.9697 22.461C48.6256 23.1246 48.9961 24.025 49 24.9654Z\" fill=\"#004BD1\"\/>\n<path d=\"M49.0078 46.2989C49.0107 47.0028 48.8078 47.6916 48.425 48.2783C48.0422 48.8649 47.4966 49.3229 46.8573 49.5943C46.2181 49.8657 45.5139 49.9383 44.834 49.8028C44.1541 49.6673 43.5291 49.3298 43.0381 48.8331C42.5472 48.3365 42.2124 47.703 42.0761 47.0129C41.9399 46.3228 42.0084 45.6071 42.2729 44.9565C42.5373 44.306 42.9859 43.7498 43.5617 43.3585C44.1376 42.9671 44.8149 42.7583 45.5078 42.7583C46.4335 42.7583 47.3215 43.1308 47.9775 43.7944C48.6334 44.458 49.0039 45.3585 49.0078 46.2989Z\" fill=\"#004BD1\"\/>\n<path d=\"M49 67.7064C49 68.4096 48.7948 69.0969 48.4102 69.6816C48.0256 70.2663 47.4789 70.7221 46.8394 70.9912C46.1998 71.2603 45.4961 71.3307 44.8172 71.1935C44.1383 71.0563 43.5146 70.7177 43.0251 70.2204C42.5356 69.7232 42.2023 69.0897 42.0673 68.4C41.9322 67.7103 42.0015 66.9954 42.2664 66.3458C42.5313 65.6961 42.9799 65.1407 43.5555 64.7501C44.131 64.3594 44.8077 64.1509 45.5 64.1509C46.4282 64.1509 47.3185 64.5255 47.9749 65.1923C48.6313 65.859 49 66.7634 49 67.7064Z\" fill=\"#004BD1\"\/>\n<path d=\"M49.0078 89.0399C49.0078 89.7431 48.8025 90.4305 48.418 91.0152C48.0334 91.5999 47.4867 92.0556 46.8472 92.3247C46.2076 92.5938 45.5039 92.6642 44.825 92.527C44.1461 92.3898 43.5224 92.0512 43.0329 91.5539C42.5434 91.0567 42.2101 90.4232 42.0751 89.7335C41.94 89.0438 42.0093 88.329 42.2742 87.6793C42.5391 87.0296 42.9877 86.4743 43.5633 86.0836C44.1388 85.6929 44.8155 85.4844 45.5078 85.4844C45.9679 85.4824 46.424 85.5731 46.8495 85.7511C47.275 85.9291 47.6616 86.1909 47.987 86.5214C48.3123 86.852 48.5701 87.2447 48.7453 87.6769C48.9205 88.1092 49.0097 88.5724 49.0078 89.0399Z\" fill=\"#004BD1\"\/>\n<path d=\"M28 3.64678C28 4.34999 27.7947 5.03741 27.4101 5.6221C27.0255 6.20679 26.4789 6.66248 25.8394 6.93159C25.1998 7.20069 24.4961 7.27117 23.8172 7.13398C23.1383 6.99679 22.5146 6.65813 22.0251 6.16089C21.5356 5.66366 21.2023 5.03017 21.0673 4.34048C20.9322 3.65079 21.0015 2.93585 21.2664 2.28617C21.5313 1.6365 21.9799 1.08126 22.5555 0.690577C23.131 0.299899 23.8077 0.0913092 24.5 0.0913091C25.4282 0.0913089 26.3185 0.465987 26.9749 1.13276C27.6313 1.79954 28 2.70382 28 3.64678Z\" fill=\"#004BD1\"\/>\n<path d=\"M28 24.9654C28.0029 25.6692 27.8 26.3582 27.4172 26.9448C27.0344 27.5315 26.4888 27.9895 25.8495 28.2609C25.2103 28.5323 24.5061 28.6048 23.8262 28.4693C23.1463 28.3337 22.5213 27.9963 22.0304 27.4997C21.5394 27.0031 21.2046 26.3696 21.0683 25.6795C20.9321 24.9894 21.0005 24.2737 21.265 23.6231C21.5295 22.9726 21.9781 22.4164 22.554 22.0251C23.1298 21.6337 23.8071 21.4248 24.5 21.4248C25.4257 21.4248 26.3137 21.7974 26.9697 22.461C27.6256 23.1246 27.9961 24.025 28 24.9654Z\" fill=\"#004BD1\"\/>\n<path d=\"M28.0078 46.2989C28.0107 47.0028 27.8078 47.6916 27.425 48.2783C27.0422 48.8649 26.4966 49.3229 25.8574 49.5943C25.2181 49.8657 24.5139 49.9383 23.834 49.8028C23.1541 49.6673 22.5291 49.3298 22.0382 48.8331C21.5472 48.3365 21.2124 47.703 21.0762 47.0129C20.9399 46.3228 21.0083 45.6071 21.2728 44.9565C21.5373 44.306 21.9859 43.7498 22.5618 43.3585C23.1376 42.9671 23.8149 42.7583 24.5078 42.7583C25.4335 42.7583 26.3215 43.1308 26.9775 43.7944C27.6334 44.458 28.0039 45.3585 28.0078 46.2989Z\" fill=\"#004BD1\"\/>\n<path d=\"M28 67.7064C28 68.4096 27.7947 69.0969 27.4101 69.6816C27.0255 70.2663 26.4789 70.7221 25.8394 70.9912C25.1998 71.2603 24.4961 71.3307 23.8172 71.1935C23.1383 71.0563 22.5146 70.7177 22.0251 70.2204C21.5356 69.7232 21.2023 69.0897 21.0673 68.4C20.9322 67.7103 21.0015 66.9954 21.2664 66.3458C21.5313 65.6961 21.9799 65.1407 22.5555 64.7501C23.131 64.3594 23.8077 64.1509 24.5 64.1509C25.4282 64.1509 26.3185 64.5255 26.9749 65.1923C27.6313 65.859 28 66.7634 28 67.7064Z\" fill=\"#004BD1\"\/>\n<path d=\"M28.0078 89.0399C28.0078 89.7431 27.8024 90.4305 27.4179 91.0152C27.0333 91.5999 26.4867 92.0556 25.8472 92.3247C25.2076 92.5938 24.5039 92.6642 23.825 92.527C23.1461 92.3898 22.5224 92.0512 22.0329 91.5539C21.5434 91.0567 21.2101 90.4232 21.0751 89.7335C20.94 89.0438 21.0093 88.329 21.2742 87.6793C21.5391 87.0296 21.9877 86.4743 22.5633 86.0836C23.1388 85.6929 23.8155 85.4844 24.5078 85.4844C24.9679 85.4824 25.424 85.5731 25.8495 85.7511C26.275 85.9291 26.6616 86.1909 26.987 86.5214C27.3123 86.852 27.5701 87.2447 27.7453 87.6769C27.9205 88.1092 28.0097 88.5724 28.0078 89.0399Z\" fill=\"#004BD1\"\/>\n<path d=\"M6.99997 3.64683C6.99996 4.35066 6.7943 5.03868 6.40907 5.62369C6.02384 6.2087 5.47635 6.66443 4.83596 6.9331C4.19556 7.20176 3.49106 7.27125 2.81173 7.13285C2.13241 6.99446 1.50879 6.65441 1.0199 6.15568C0.531009 5.65695 0.198876 5.02203 0.0654865 4.33136C-0.0679026 3.64069 0.00346458 2.92527 0.270617 2.27586C0.537769 1.62645 0.98862 1.07223 1.56611 0.683347C2.1436 0.294462 2.82178 0.0883954 3.51463 0.0913402C3.97356 0.091336 4.42796 0.183422 4.85177 0.362283C5.27559 0.541143 5.66049 0.803264 5.98433 1.13362C6.30816 1.46397 6.5646 1.85611 6.73889 2.28739C6.91318 2.71867 7.0019 3.18062 6.99997 3.64683Z\" fill=\"#004BD1\"\/>\n<path d=\"M6.99997 24.9649C7.00287 25.6694 6.79969 26.3589 6.41622 26.9459C6.03275 27.5329 5.48627 27.9909 4.84614 28.2618C4.206 28.5328 3.50104 28.6044 2.82075 28.4677C2.14045 28.331 1.51552 27.9921 1.02515 27.494C0.534791 26.9958 0.201114 26.3609 0.0665336 25.6698C-0.0680471 24.9787 0.00253189 24.2626 0.269251 23.6123C0.53597 22.962 0.986764 22.4069 1.56457 22.0174C2.14238 21.6278 2.82114 21.4214 3.51462 21.4243C4.43899 21.4243 5.32551 21.7975 5.97914 22.4614C6.63277 23.1254 6.99997 24.0259 6.99997 24.9649Z\" fill=\"#004BD1\"\/>\n<path d=\"M7.00705 46.2995C7.0216 47.0063 6.82836 47.7015 6.45207 48.2962C6.07579 48.8909 5.53358 49.3582 4.89459 49.6383C4.25561 49.9184 3.54892 49.9987 2.86482 49.8688C2.18072 49.7389 1.5502 49.4048 1.05394 48.9092C0.55768 48.4135 0.218212 47.7788 0.0787807 47.0862C-0.0606508 46.3936 0.00634421 45.6744 0.27122 45.0206C0.536095 44.3669 0.986753 43.8081 1.56574 43.4158C2.14472 43.0236 2.82575 42.8156 3.52168 42.8184C4.44606 42.8184 5.33258 43.1914 5.98622 43.8554C6.63985 44.5194 7.00705 45.42 7.00705 46.359\" fill=\"#004BD1\"\/>\n<path d=\"M6.99997 67.7064C6.99996 68.4103 6.7943 69.0982 6.40907 69.6832C6.02384 70.2683 5.47635 70.724 4.83596 70.9927C4.19556 71.2613 3.49106 71.3308 2.81173 71.1924C2.13241 71.054 1.50879 70.714 1.0199 70.2152C0.531009 69.7165 0.198876 69.0816 0.0654865 68.3909C-0.0679026 67.7002 0.00346458 66.9849 0.270617 66.3355C0.537769 65.686 0.98862 65.1317 1.56611 64.7428C2.1436 64.3539 2.82178 64.148 3.51463 64.1509C3.97356 64.1509 4.42796 64.243 4.85177 64.4219C5.27559 64.6007 5.66049 64.8628 5.98433 65.1932C6.30816 65.5236 6.5646 65.9156 6.73889 66.3469C6.91318 66.7782 7.0019 67.2402 6.99997 67.7064Z\" fill=\"#004BD1\"\/>\n<path d=\"M7.00769 89.0399C7.00768 89.7437 6.80203 90.4318 6.4168 91.0168C6.03157 91.6018 5.48409 92.0574 4.8437 92.3261C4.20332 92.5948 3.49882 92.6643 2.81951 92.5259C2.14019 92.3875 1.51659 92.0474 1.0277 91.5487C0.538815 91.0499 0.206686 90.415 0.073298 89.7243C-0.0600891 89.0337 0.0112771 88.3183 0.278425 87.6689C0.545574 87.0195 0.996419 86.4652 1.5739 86.0763C2.15139 85.6874 2.82956 85.4815 3.52239 85.4844C3.98187 85.4824 4.43715 85.5731 4.86185 85.7513C5.28654 85.9294 5.67222 86.1915 5.99644 86.5222C6.32066 86.853 6.57695 87.2458 6.75054 87.678C6.92414 88.1102 7.01157 88.5731 7.00769 89.0399Z\" fill=\"#004BD1\"\/>\n<\/svg>\n<\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-238","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/werkado.eu\/lv\/wp-json\/wp\/v2\/pages\/238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/werkado.eu\/lv\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/werkado.eu\/lv\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/werkado.eu\/lv\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/werkado.eu\/lv\/wp-json\/wp\/v2\/comments?post=238"}],"version-history":[{"count":5,"href":"https:\/\/werkado.eu\/lv\/wp-json\/wp\/v2\/pages\/238\/revisions"}],"predecessor-version":[{"id":6251,"href":"https:\/\/werkado.eu\/lv\/wp-json\/wp\/v2\/pages\/238\/revisions\/6251"}],"wp:attachment":[{"href":"https:\/\/werkado.eu\/lv\/wp-json\/wp\/v2\/media?parent=238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}